{"id":86845,"date":"2026-07-13T10:34:24","date_gmt":"2026-07-13T08:34:24","guid":{"rendered":"https:\/\/megapelican.com\/si\/izdelek\/casavella-rocni-aparat-za-pripravo-testenin-cavatelli\/"},"modified":"2026-07-13T10:34:27","modified_gmt":"2026-07-13T08:34:27","slug":"casavella-rocni-aparat-za-pripravo-testenin-cavatelli","status":"publish","type":"product","link":"https:\/\/megapelican.com\/si\/izdelek\/casavella-rocni-aparat-za-pripravo-testenin-cavatelli\/","title":{"rendered":"CasaVella\u2122 ro\u010dni aparat za pripravo testenin cavatelli"},"content":{"rendered":"<div class=\"smania_landing_description_title\">NOVO: Priprava doma\u010dih testenin brez truda<\/div>\n<div class=\"smania_landing_description_txt\">Sve\u017ee testenine. Ro\u010dno izdelana popolnost!<\/div>\n<div class=\"smania_landing_description_subtitle\">Trpe\u017een ro\u010dni aparat za testenine z aluminijastim ohi\u0161jem, nastavljivo namizno spono in okolju prijaznim ro\u010dajem za enostavno pripravo doma\u010dih testenin cavatelli in makaronov.<\/div>\n<div class=\"smania_landing_description_list\">\n<ul>\n<li>Trpe\u017ena aluminijeva zlitina, odporna proti rji<\/li>\n<li>Okolju prijazen dizajn z ro\u010dnim pogonom<\/li>\n<li>Brez porabe elektri\u010dne energije<\/li>\n<li>Kompaktna velikost za vsako kuhinjo<\/li>\n<li>Varne in zdrave doma\u010de testenine<\/li>\n<li>Enostavno \u010di\u0161\u010denje po uporabi<\/li>\n<\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pripravi popolne cavatellije in makarone|Varna in nastavljiva namizna spona|Snemljiv ro\u010daj za enostavno shranjevanje|Stabilno in robustno kovinsko ohi\u0161je|Preprosto delovanje v samo 4 korakih|Dimenzije: 21 cm x 11 cm|Ro\u010daj (ro\u010dica): 6,5 cm|Odprtina spone: do 3 cm|Material: aluminijeva zlitina, \u017eelezo, ABS|Te\u017ea: 860 g<\/p>\n","protected":false},"featured_media":86844,"template":"","meta":{"_acf_changed":false},"product_cat":[223],"product_tag":[573],"acf":[],"_links":{"self":[{"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/product\/86845"}],"collection":[{"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/media\/86844"}],"wp:attachment":[{"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/media?parent=86845"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/product_cat?post=86845"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/megapelican.com\/si\/wp-json\/wp\/v2\/product_tag?post=86845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}